{"id":17402975,"date":"2025-09-15T14:29:26","date_gmt":"2025-09-15T14:29:26","guid":{"rendered":"https:\/\/wpml.org\/annonces-fr\/2025\/09\/woocommerce-multilingual-renomme-en-wpml-multilingual-multicurrency-for-woocommerce\/"},"modified":"2026-02-26T07:11:33","modified_gmt":"2026-02-26T07:11:33","slug":"woocommerce-multilingual-renomme-en-wpml-multilingual-multicurrency-for-woocommerce","status":"publish","type":"post","link":"https:\/\/wpml.org\/fr\/compatibilite\/2025\/09\/woocommerce-multilingual-renomme-en-wpml-multilingual-multicurrency-for-woocommerce\/","title":{"rendered":"WooCommerce Multilingual renomm\u00e9 en WPML Multilingual &amp; Multicurrency for WooCommerce"},"content":{"rendered":"\n<p class=\"lead\">Notre extension, pr\u00e9c\u00e9demment appel\u00e9e WooCommerce Multilingual &amp; Multicurrency, porte d\u00e9sormais un nouveau nom : WPML Multilingual &amp; Multicurrency for WooCommerce.<\/p>\n\n<p>Ce changement fait suite \u00e0 une demande de WordPress.org concernant les r\u00e8gles de marque d\u00e9pos\u00e9e de WooCommerce. Nous respectons pleinement ces r\u00e8gles et avons mis \u00e0 jour le nom du plugin en cons\u00e9quence. <\/p>\n\n<h2 class=\"wp-block-heading\">Ce que cela signifie<\/h2>\n\n<p>Mis \u00e0 part le nouveau nom, rien ne change :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Le plugin fonctionne exactement comme avant<\/li>\n\n\n\n<li>Toutes les fonctionnalit\u00e9s restent les m\u00eames<br\/><\/li>\n<\/ul>\n\n<p>Dans l\u2019administration WordPress, l\u2019\u00e9cran sous WooCommerce, pr\u00e9c\u00e9demment nomm\u00e9 <strong>WooCommerce Multilingual &amp; Multicurrency<\/strong>, s\u2019appelle d\u00e9sormais <strong>WPML Multilingual &amp; Multicurrency for WooCommerce<\/strong>.<\/p>\n\n<figure class=\"wp-block-image tb-image tb-image-dynamic tb-image-frame-none\" data-toolset-blocks-image=\"20771f4bf613445faf763e17768499e2\"><a href=\"https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/wcml-name-change.png\"><img decoding=\"async\" width=\"1084\" height=\"685\" loading=\"lazy\" src=\"https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/wcml-name-change.png\" alt=\"\" class=\"wp-image-17387672\" srcset=\"https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/wcml-name-change.png 1084w, https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/wcml-name-change-300x190.png 300w, https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/wcml-name-change-1024x647.png 1024w, https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/wcml-name-change-150x95.png 150w, https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/wcml-name-change-768x485.png 768w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\" \/><\/a><figcaption><div class=\"tb-image-caption\">\u00c9cran d&rsquo;administration WPML renomm\u00e9 dans la section WooCommerce<\/div><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Quand vous verrez la mise \u00e0 jour<\/h2>\n\n<p>Nous venons de publier la version <strong>5.5.2.1<\/strong>, qui met \u00e0 jour le nom du plugin.<\/p>\n\n<p>Cette version est d\u00e9ploy\u00e9e par lots. Une fois qu&rsquo;elle sera disponible sur votre site, vous verrez le nouveau nom dans votre liste de plugins et dans le menu d&rsquo;administration. Comme il n&rsquo;y a pas d&rsquo;autres changements dans cette version, vous n&rsquo;avez rien \u00e0 faire.  <\/p>\n\n<h2 class=\"wp-block-heading\">Continuez \u00e0 utiliser le plugin comme d&rsquo;habitude<\/h2>\n\n<p>Aucune action n&rsquo;est requise de votre part et vous pouvez continuer \u00e0 utiliser le plugin comme toujours.<\/p>\n\n<p>Si vous avez des questions, laissez-nous simplement un commentaire ci-dessous et nous vous r\u00e9pondrons.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre extension, pr\u00e9c\u00e9demment appel\u00e9e WooCommerce Multilingual &amp; Multicurrency, porte d\u00e9sormais un nouveau nom : WPML Multilingual &amp; Multicurrency for WooCommerce. Ce changement fait suite \u00e0 une demande de WordPress.org concernant les r\u00e8gles de marque d\u00e9pos\u00e9e de WooCommerce. Nous respectons pleinement ces r\u00e8gles et avons mis \u00e0 jour le nom du plugin en cons\u00e9quence. Ce que [&hellip;]<\/p>\n","protected":false},"author":76577,"featured_media":17387691,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_uag_custom_page_level_css":"","ep_exclude_from_search":false,"footnotes":""},"categories":[10964],"tags":[],"class_list":["post-17402975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-compatibilite"],"spectra_custom_meta":{"_pingme":["1"],"_encloseme":["1"],"_subscription_coupon_product_id":["0"],"_wpv_contains_gutenberg_views":[""],"_alp_processed":["1772089893"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"toolset_post_editor_mode":["block"],"_yoast_wpseo_primary_category":["1371"],"_yoast_wpseo_opengraph-image":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full-fb-1024x536.png"],"_yoast_wpseo_twitter-image":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full-X.png"],"_thumbnail_id":["17387691"],"_last_translation_edit_mode":["translation-editor"],"_wpml_word_count":["260"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_css_file_name":["uag-css-17402975.css"]},"uagb_featured_image_src":{"full":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full.png",1024,800,false],"thumbnail":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full-150x117.png",150,117,true],"medium":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full-300x234.png",300,234,true],"medium_large":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full-768x600.png",768,600,true],"large":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full.png",1024,800,false],"1536x1536":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full.png",1024,800,false],"2048x2048":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full.png",1024,800,false],"gform-image-choice-sm":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full.png",300,234,false],"gform-image-choice-md":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full.png",400,313,false],"gform-image-choice-lg":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full.png",600,469,false],"woocommerce_thumbnail":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full-150x150.png",150,150,true],"woocommerce_single":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full-300x234.png",300,234,true],"woocommerce_gallery_thumbnail":["https:\/\/wpml.org\/wp-content\/uploads\/2025\/09\/WCML-5.5.2.1-Full-100x100.png",100,100,true]},"uagb_author_info":{"display_name":"Dario","author_link":"https:\/\/wpml.org\/fr\/author\/darioh\/"},"uagb_comment_info":0,"uagb_excerpt":"Notre extension, pr\u00e9c\u00e9demment appel\u00e9e WooCommerce Multilingual &amp; Multicurrency, porte d\u00e9sormais un nouveau nom : WPML Multilingual &amp; Multicurrency for WooCommerce. Ce changement fait suite \u00e0 une demande de WordPress.org concernant les r\u00e8gles de marque d\u00e9pos\u00e9e de WooCommerce. Nous respectons pleinement ces r\u00e8gles et avons mis \u00e0 jour le nom du plugin en cons\u00e9quence. Ce que\u2026","_links":{"self":[{"href":"https:\/\/wpml.org\/fr\/wp-json\/wp\/v2\/posts\/17402975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wpml.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wpml.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wpml.org\/fr\/wp-json\/wp\/v2\/users\/76577"}],"replies":[{"embeddable":true,"href":"https:\/\/wpml.org\/fr\/wp-json\/wp\/v2\/comments?post=17402975"}],"version-history":[{"count":5,"href":"https:\/\/wpml.org\/fr\/wp-json\/wp\/v2\/posts\/17402975\/revisions"}],"predecessor-version":[{"id":17853694,"href":"https:\/\/wpml.org\/fr\/wp-json\/wp\/v2\/posts\/17402975\/revisions\/17853694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wpml.org\/fr\/wp-json\/wp\/v2\/media\/17387691"}],"wp:attachment":[{"href":"https:\/\/wpml.org\/fr\/wp-json\/wp\/v2\/media?parent=17402975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wpml.org\/fr\/wp-json\/wp\/v2\/categories?post=17402975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wpml.org\/fr\/wp-json\/wp\/v2\/tags?post=17402975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}