{"id":21543,"count":5,"description":"","link":"https:\/\/wpml.org\/zh-hans\/site-theme\/genesis-sample\/","name":"Genesis sample","slug":"genesis-sample","taxonomy":"site-theme","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/wpml.org\/zh-hans\/wp-json\/wp\/v2\/site-theme\/21543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wpml.org\/zh-hans\/wp-json\/wp\/v2\/site-theme"}],"about":[{"href":"https:\/\/wpml.org\/zh-hans\/wp-json\/wp\/v2\/taxonomies\/site-theme"}]}}